{"id":3252,"date":"2025-02-20T11:38:54","date_gmt":"2025-02-20T11:38:54","guid":{"rendered":"https:\/\/nordhus.dk\/?page_id=3252"},"modified":"2026-01-26T15:10:39","modified_gmt":"2026-01-26T15:10:39","slug":"meetings","status":"publish","type":"page","link":"https:\/\/devnordhus.demo.supertusch.com\/en\/meetings\/","title":{"rendered":"MEETING PACKAGES"},"content":{"rendered":"<div class=\"hero-section relative\">\n\t<div class=\"hero-section-top\" style='background-color:rgb(0,0,0);color:#ffffff;'>\n\t\t<div class=\"container mx-auto\">\n\t\t\t<div class=\"flex justify-between gap-[7.9375rem] pt-5 pb-5 sm:pb-10 px-4 sm:px-10\">\n\t\t\t\t<div class=\"container-top sm:w-[75%]\">\n\t\t\t\t\t<h1 class=\"wp-block-heading !mb-0 uppercase\"><strong>MEETING PACKAGES AT NORDHUS<\/strong><\/h1>\n\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"wp-block-heading mt-5 sm:mt-10 !mb-0\">IN NORDHUS, YOU CAN HOST YOUR MEETING. Centrally located in Copenhagen, in the city&#8217;s newest cultural hub, it&#8217;s the perfect base for meetings, appointments, or conferences.  <\/h3>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"hidden lg:flex flex-row items-end sm:w-60\">\n\t\t\t\t\t\t<!-- bg-highlight-pink bg-highlight-green bg-highlight-cyan hover:bg-highlight-pink hover:bg-highlight-green hover:bg-highlight-cyan -->\n\t\t\t\t\t\t<div class=\"hero-section-arrow-wrapper max-h-[6.75rem] h-full overflow-hidden\"><a href=\"#hero-section-breakpoint\" class=\"block relative top-0 hover:-top-full transition-all filter-color-white\"><\/a><\/div>\n\t\t\t\t\t\t<div class=\"hero-section-arrow-wrapper max-h-[6.75rem] h-full overflow-hidden\"><a href=\"#hero-section-breakpoint\" class=\"block relative top-0 hover:-top-full transition-all filter-color-white\"><\/a><\/div>\n\t\t\t\t\t\t<div class=\"hero-section-arrow-wrapper max-h-[6.75rem] h-full overflow-hidden\"><a href=\"#hero-section-breakpoint\" class=\"block relative top-0 hover:-top-full transition-all filter-color-white\"><\/a><\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t<\/div>\n<div id=\"hero-section-breakpoint\"><\/div>\n<div class=\"full-image-section mb-[-1px]\" >\n\t<img loading=\"lazy\" decoding=\"async\" width=\"1828\" height=\"2560\" src=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/img_2405-scaled.jpg\" class=\"w-full h-full max-h-[247px] sm:max-h-[538px] object-cover\" alt=\"\" srcset=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/img_2405-scaled.jpg 1828w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/img_2405-214x300.jpg 214w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/img_2405-731x1024.jpg 731w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/img_2405-768x1075.jpg 768w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/img_2405-1097x1536.jpg 1097w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/img_2405-1463x2048.jpg 1463w\" sizes=\"auto, (max-width: 1828px) 100vw, 1828px\" \/><\/div>\n<div class=\"two-column-text-section\" style='background-color:rgb(255,255,255);' >\n\t<div class=\"container mx-auto add-spacing\">\n\t\t<div class=\"flex flex-col sm:gap-10 p-4 sm:p-10\">\n\t\t\t<div class=\"flex max-w-[668px]\">\n\t\t\t\t<h2 class=\"wp-block-heading !mb-0\" style='color:#000000;'>HOLD A MEETING AT NORDHUS<\/h2>\n\t\t\t<\/div>\n\t\t\t<div class=\"flex flex-col sm:flex-row items-end gap-10\">\n\t\t\t\t<div class=\"sm:basis-1\/2 flex flex-col justify-between\">\n\t\t\t\t\t<div class=\"wysiwyg\" style='color:#000000;'>\n\t\t\t\t\t\t<p data-start=\"0\" data-end=\"278\">Hold your next meeting in the inspiring and lively setting of Nordhus. We offer functional spaces where both the surroundings and the culinary experience create a seamless and comfortable atmosphere. Our kitchen focuses on fresh, flavorful, and 100% organic dishes, and we take care of everything from lunch and coffee to refreshments. See our meeting packages below, or contact us at <a rel=\"noopener\" data-start=\"411\" data-end=\"425\">hej@nordhus.dk <\/a>for a tailored offer that meets your specific needs.   <\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"sm:basis-1\/2 flex flex-col justify-between\">\n\t\t\t\t\t<div class=\"wysiwyg\" style='color:#000000;'>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"cta flex flex-col sm:flex-row gap-3 sm:gap-5 mt-8 sm:mt-10 items-start\" style=\"justify-content: start\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<!--  content-baseline content-center content-end -->\n<div class=\"two-column-text-media-section\" style='background-color:rgb(0,0,0);'>\n\t<div class=\"container mx-auto\">\n\t\t<div class=\"flex flex-col sm:flex-row items-stretch gap-5 sm:gap-10 p-4 sm:p-10\">\n\t\t\t<div class=\"media-wrapper sm:basis-1\/2\">\n\t\t\t\t<h2 class=\"block sm:hidden wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>DAY MEETING<strong><\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sm:basis-1\/2 grid content-between\">\n\t\t\t\t<h2 class=\"hidden sm:block wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>DAY MEETING<strong><\/h2>\n\t\t\t\t<div class=\"text-content\">\n\t\t\t\t\t<div class=\"wysiwyg\" style='color:#ffffff;'>\n\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>8.00-16.00<\/strong><\/p>\n<ul style=\"text-align: left;\">\n<li>Bun with cheese<\/li>\n<li>Lunch<\/li>\n<li>Cake<\/li>\n<li>Soda, 1 per person<\/li>\n<li>Coffee and tea, unlimited.<\/li>\n<li>Sparkling water, unlimited.<\/li>\n<li>Room rental<\/li>\n<li>Screen and flipchart<\/li>\n<li>Wi-Fi internet<\/li>\n<\/ul>\n<p class=\"p1\" style=\"text-align: left;\"><b>680 kr. \u2013 per person, excluding VAT <\/b><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"cta flex flex-col sm:flex-row gap-3 sm:gap-5 mt-5 sm:mt-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:hej@nordhus.dk\" target=\"_self\" class=\"btn hover:!bg-highlight-pink hover:!ring-highlight-pink line-white text-center uppercase basis-1\/2 sm:basis-auto font-bold sm:font-normal\">Book her<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><!--  content-baseline content-center content-end -->\n<div class=\"two-column-text-media-section\" style='background-color:rgb(0,0,0);'>\n\t<div class=\"container mx-auto\">\n\t\t<div class=\"flex flex-col sm:flex-row items-stretch gap-5 sm:gap-10 p-4 sm:p-10\">\n\t\t\t<div class=\"media-wrapper sm:basis-1\/2\">\n\t\t\t\t<h2 class=\"block sm:hidden wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>FULL-DAY MEETING<strong><\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2400\" src=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/2u8a4920ny.jpg\" class=\"object-cover w-full aspect-[1\/1]\" alt=\"\" srcset=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/2u8a4920ny.jpg 1920w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/2u8a4920ny-240x300.jpg 240w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/2u8a4920ny-819x1024.jpg 819w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/2u8a4920ny-768x960.jpg 768w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/2u8a4920ny-1229x1536.jpg 1229w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/2u8a4920ny-1638x2048.jpg 1638w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sm:basis-1\/2 grid content-between\">\n\t\t\t\t<h2 class=\"hidden sm:block wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>FULL-DAY MEETING<strong><\/h2>\n\t\t\t\t<div class=\"text-content\">\n\t\t\t\t\t<div class=\"wysiwyg\" style='color:#ffffff;'>\n\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"s2\"><b>8.00-19.30<br \/>\n<\/b><\/span><\/p>\n<ul style=\"text-align: left;\">\n<li>Bun with cheese<\/li>\n<li>Lunch<\/li>\n<li>Cake<\/li>\n<li>Soda, 1 per person<\/li>\n<li>Coffee and tea, unlimited.<\/li>\n<li>Sparkling water, unlimited.<\/li>\n<li>Room rental<\/li>\n<li>Screen and flipchart<\/li>\n<li>Wi-Fi internet<\/li>\n<li><span class=\"s2\">Community Dinner<\/span> &#8211; <i>(Beverages purchased on the day)<\/i><\/li>\n<\/ul>\n<p class=\"p3\" style=\"text-align: left;\"><b>800 kr. \u2013 pr. person excluding VAT <\/b><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"cta flex flex-col sm:flex-row gap-3 sm:gap-5 mt-5 sm:mt-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:hej@nordhus.dk\" target=\"_self\" class=\"btn hover:!bg-highlight-pink hover:!ring-highlight-pink line-white text-center uppercase basis-1\/2 sm:basis-auto font-bold sm:font-normal\">Book her<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><!--  content-baseline content-center content-end -->\n<div class=\"two-column-text-media-section\" style='background-color:rgb(0,0,0);'>\n\t<div class=\"container mx-auto\">\n\t\t<div class=\"flex flex-col sm:flex-row items-stretch gap-5 sm:gap-10 p-4 sm:p-10\">\n\t\t\t<div class=\"media-wrapper sm:basis-1\/2\">\n\t\t\t\t<h2 class=\"block sm:hidden wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>HALF-DAY MEETING<strong><\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"2560\" src=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/dinner-scaled.jpg\" class=\"object-cover w-full aspect-[1\/1]\" alt=\"\" srcset=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/dinner-scaled.jpg 1920w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/dinner-225x300.jpg 225w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/dinner-768x1024.jpg 768w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/dinner-1152x1536.jpg 1152w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/dinner-1536x2048.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sm:basis-1\/2 grid content-between\">\n\t\t\t\t<h2 class=\"hidden sm:block wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>HALF-DAY MEETING<strong><\/h2>\n\t\t\t\t<div class=\"text-content\">\n\t\t\t\t\t<div class=\"wysiwyg\" style='color:#ffffff;'>\n\t\t\t\t\t\t<p><span class=\"s2\"><b>08.00-12.00<br \/>\n<\/b><\/span><\/p>\n<ul>\n<li>Bun with cheese<\/li>\n<li>Lunch<\/li>\n<li>Soda, 1 per person<\/li>\n<li>Coffee and tea, unlimited.<\/li>\n<li>Sparkling water, unlimited.<\/li>\n<li>Room rental<\/li>\n<li>Screen and flipchart<\/li>\n<li>Wi-Fi internet<\/li>\n<\/ul>\n<p class=\"p1\"><b>520 kr. \u2013 per person, excluding VAT <\/b><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"cta flex flex-col sm:flex-row gap-3 sm:gap-5 mt-5 sm:mt-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:hej@nordhus.dk\" target=\"_self\" class=\"btn hover:!bg-highlight-pink hover:!ring-highlight-pink line-white text-center uppercase basis-1\/2 sm:basis-auto font-bold sm:font-normal\">Book her<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><!--  content-baseline content-center content-end -->\n<div class=\"two-column-text-media-section\" style='background-color:rgb(0,0,0);'>\n\t<div class=\"container mx-auto\">\n\t\t<div class=\"flex flex-col sm:flex-row items-stretch gap-5 sm:gap-10 p-4 sm:p-10\">\n\t\t\t<div class=\"media-wrapper sm:basis-1\/2\">\n\t\t\t\t<h2 class=\"block sm:hidden wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>HALF-DAY MEETING<strong><\/h2>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2048\" height=\"2560\" src=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/nordhussal_2-scaled.jpg\" class=\"object-cover w-full aspect-[1\/1]\" alt=\"\" srcset=\"https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/nordhussal_2-scaled.jpg 2048w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/nordhussal_2-240x300.jpg 240w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/nordhussal_2-819x1024.jpg 819w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/nordhussal_2-768x960.jpg 768w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/nordhussal_2-1229x1536.jpg 1229w, https:\/\/devnordhus.demo.supertusch.com\/wp-content\/uploads\/2025\/02\/nordhussal_2-1638x2048.jpg 1638w\" sizes=\"auto, (max-width: 2048px) 100vw, 2048px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<div class=\"sm:basis-1\/2 grid content-between\">\n\t\t\t\t<h2 class=\"hidden sm:block wp-block-heading uppercase 1\" style='color:#ffffff;'><strong>HALF-DAY MEETING<strong><\/h2>\n\t\t\t\t<div class=\"text-content\">\n\t\t\t\t\t<div class=\"wysiwyg\" style='color:#ffffff;'>\n\t\t\t\t\t\t<p style=\"text-align: left;\"><span class=\"s2\"><b>12.00-16.00<br \/>\n<\/b><\/span><\/p>\n<ul style=\"text-align: left;\">\n<li>Lunch<\/li>\n<li>Cake<\/li>\n<li>Soda, 1 per person<\/li>\n<li>Coffee and tea, unlimited.<\/li>\n<li>Sparkling water, unlimited.<\/li>\n<li>Room rental<\/li>\n<li>Screen and flipchart<\/li>\n<li>Wi-Fi internet<\/li>\n<\/ul>\n<p class=\"p1\" style=\"text-align: left;\"><b>520 kr. \u2013 per person, excluding VAT <\/b><\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"cta flex flex-col sm:flex-row gap-3 sm:gap-5 mt-5 sm:mt-10\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"mailto:hej@nordhus.dk\" target=\"_blank\" class=\"btn hover:!bg-highlight-green hover:!ring-highlight-green line-white text-center uppercase basis-1\/2 sm:basis-auto font-bold sm:font-normal\">Book her<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3252","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MEETING PACKAGES - Nordhus<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MEETING PACKAGES - Nordhus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/\" \/>\n<meta property=\"og:site_name\" content=\"Nordhus\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100082961870934\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-26T15:10:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/\",\"url\":\"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/\",\"name\":\"MEETING PACKAGES - Nordhus\",\"isPartOf\":{\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/#website\"},\"datePublished\":\"2025-02-20T11:38:54+00:00\",\"dateModified\":\"2026-01-26T15:10:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/devnordhus.demo.supertusch.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MEETING PACKAGES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/#website\",\"url\":\"https:\/\/devnordhus.demo.supertusch.com\/\",\"name\":\"Nordhus\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/devnordhus.demo.supertusch.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/#organization\",\"name\":\"Nordhus\",\"url\":\"https:\/\/devnordhus.demo.supertusch.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/nordhus.dk\/wp-content\/uploads\/2024\/08\/logo-dark.svg\",\"contentUrl\":\"https:\/\/nordhus.dk\/wp-content\/uploads\/2024\/08\/logo-dark.svg\",\"width\":1400,\"height\":314,\"caption\":\"Nordhus\"},\"image\":{\"@id\":\"https:\/\/devnordhus.demo.supertusch.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/profile.php?id=100082961870934\",\"https:\/\/www.instagram.com\/nordhus_cph\/\",\"https:\/\/www.linkedin.com\/company\/nordhuscph\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MEETING PACKAGES - Nordhus","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"en_US","og_type":"article","og_title":"MEETING PACKAGES - Nordhus","og_url":"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/","og_site_name":"Nordhus","article_publisher":"https:\/\/www.facebook.com\/profile.php?id=100082961870934","article_modified_time":"2026-01-26T15:10:39+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/","url":"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/","name":"MEETING PACKAGES - Nordhus","isPartOf":{"@id":"https:\/\/devnordhus.demo.supertusch.com\/#website"},"datePublished":"2025-02-20T11:38:54+00:00","dateModified":"2026-01-26T15:10:39+00:00","breadcrumb":{"@id":"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/devnordhus.demo.supertusch.com\/moedepakker\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/devnordhus.demo.supertusch.com\/en\/"},{"@type":"ListItem","position":2,"name":"MEETING PACKAGES"}]},{"@type":"WebSite","@id":"https:\/\/devnordhus.demo.supertusch.com\/#website","url":"https:\/\/devnordhus.demo.supertusch.com\/","name":"Nordhus","description":"","publisher":{"@id":"https:\/\/devnordhus.demo.supertusch.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/devnordhus.demo.supertusch.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/devnordhus.demo.supertusch.com\/#organization","name":"Nordhus","url":"https:\/\/devnordhus.demo.supertusch.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/devnordhus.demo.supertusch.com\/#\/schema\/logo\/image\/","url":"https:\/\/nordhus.dk\/wp-content\/uploads\/2024\/08\/logo-dark.svg","contentUrl":"https:\/\/nordhus.dk\/wp-content\/uploads\/2024\/08\/logo-dark.svg","width":1400,"height":314,"caption":"Nordhus"},"image":{"@id":"https:\/\/devnordhus.demo.supertusch.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100082961870934","https:\/\/www.instagram.com\/nordhus_cph\/","https:\/\/www.linkedin.com\/company\/nordhuscph\/"]}]}},"_links":{"self":[{"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/pages\/3252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/comments?post=3252"}],"version-history":[{"count":7,"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/pages\/3252\/revisions"}],"predecessor-version":[{"id":6737,"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/pages\/3252\/revisions\/6737"}],"wp:attachment":[{"href":"https:\/\/devnordhus.demo.supertusch.com\/en\/wp-json\/wp\/v2\/media?parent=3252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}